{"id":1532,"date":"2013-01-28T21:17:53","date_gmt":"2013-01-28T20:17:53","guid":{"rendered":"http:\/\/www.senecacf.net\/?p=1532"},"modified":"2013-01-28T21:17:53","modified_gmt":"2013-01-28T20:17:53","slug":"convocatoria-seleccion-cordobesa-cadete-2","status":"publish","type":"post","link":"https:\/\/www.senecacf.net\/senecacfnet\/convocatoria-seleccion-cordobesa-cadete-2\/","title":{"rendered":"Convocatoria selecci\u00f3n Cordobesa Cadete"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Los jugadores\u00a0cadetes\u00a0citados con la\u00a0selecci\u00f3n\u00a0cordobesa, a partir<\/p>\n<p>del d\u00eda 30-1-13 a las 16.15 horas en el campo de miralbaida:<\/p>\n<p>&nbsp;<\/p>\n<p>JESUS GUARDE\u00d1O, JAVIER SALAMANCA, FRANCISCO JAVIER LUQUE Y CESAR VELASCO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; Los jugadores\u00a0cadetes\u00a0citados con la\u00a0selecci\u00f3n\u00a0cordobesa, a partir del d\u00eda 30-1-13 a las 16.15 horas en el campo de miralbaida: &nbsp; JESUS GUARDE\u00d1O, JAVIER SALAMANCA, FRANCISCO JAVIER LUQUE Y CESAR VELASCO<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.senecacf.net\/senecacfnet\/wp-json\/wp\/v2\/posts\/1532"}],"collection":[{"href":"https:\/\/www.senecacf.net\/senecacfnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.senecacf.net\/senecacfnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.senecacf.net\/senecacfnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.senecacf.net\/senecacfnet\/wp-json\/wp\/v2\/comments?post=1532"}],"version-history":[{"count":1,"href":"https:\/\/www.senecacf.net\/senecacfnet\/wp-json\/wp\/v2\/posts\/1532\/revisions"}],"predecessor-version":[{"id":1533,"href":"https:\/\/www.senecacf.net\/senecacfnet\/wp-json\/wp\/v2\/posts\/1532\/revisions\/1533"}],"wp:attachment":[{"href":"https:\/\/www.senecacf.net\/senecacfnet\/wp-json\/wp\/v2\/media?parent=1532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.senecacf.net\/senecacfnet\/wp-json\/wp\/v2\/categories?post=1532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.senecacf.net\/senecacfnet\/wp-json\/wp\/v2\/tags?post=1532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}